{"id":83450,"date":"2022-08-08T12:44:50","date_gmt":"2022-08-08T10:44:50","guid":{"rendered":"https:\/\/bp2.eu\/kolorystyka-i-powloki\/"},"modified":"2026-06-03T09:20:35","modified_gmt":"2026-06-03T07:20:35","slug":"pelicule-culori-garantii","status":"publish","type":"page","link":"https:\/\/bp2.eu\/ro\/pelicule-culori-garantii\/","title":{"rendered":"PELICULE, CULORI \u0218I GARAN\u021aII"},"content":{"rendered":"\n<div class=\"wp-block-group is-style-with-b2-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-small-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center noMarginBottom has-red-color has-text-color wp-block-paragraph\"><strong>Sunt lucruri care trebuie s\u0103 fie rezistente <\/strong><\/p>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center is-style-h1 noMarginTop noMarginBottom\"><strong>PELICULE, CULORI \u0218I GARAN\u021aII<\/strong><\/h1>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-small-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group is-style-narrower-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\" style=\"font-size:22px\">Sunt mai mul\u021bi factori care influen\u021beaz\u0103 calitatea unui acoperi\u0219. Acesta trebuie s\u0103 fie durabil, capabil s\u0103 reziste la condi\u021bii meteo, s\u0103 reziste bine la perioadele calde \u0219i reci ale anului \u0219i, \u00een plus, trebuie s\u0103 fie pl\u0103cut din punct de vedere estetic. <strong>Vopselele, \u0219i mai ales propriet\u0103\u021bile lor de protec\u021bie, joac\u0103 un rol imens \u00een succesul final al acoperi\u0219ului.<\/strong><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-small-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"O\u021bel cu con\u021binut sc\u0103zut de carbon XCarb\u00ae ArcelorMittal\"><\/div>\n\n\n<h2 class=\"wp-block-heading\">O\u021bel cu con\u021binut sc\u0103zut de carbon XCarb\u00ae ArcelorMittal<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2025\/05\/Projekt-bez-nazwy-1.png\" alt=\"O\u021bel cu con\u021binut sc\u0103zut de carbon XCarb\u00ae ArcelorMittal\"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p data-renderer-start-pos=\"83\"><strong data-renderer-mark=\"true\">O\u021belul XCarb\u00ae<\/strong> provine din procese de produc\u021bie mai durabile, care <strong data-renderer-mark=\"true\">reduc emisiile de CO2<\/strong> prin utilizarea tehnologiilor moderne, precum reciclarea, reducerea consumului de energie \u0219i implementarea surselor de energie regenerabil\u0103. <strong data-renderer-mark=\"true\">XCarb\u00ae ofer\u0103 un o\u021bel cu un profil sustenabil,<\/strong> ideal pentru companiile care doresc s\u0103 \u00ee\u0219i reduc\u0103 amprenta de carbon.<\/p>\n<p data-renderer-start-pos=\"446\">O\u021belul XCarb\u00ae cu emisii reduse este produs \u00een cuptoare electrice cu arc, folosind materiale <strong data-renderer-mark=\"true\">\u00een propor\u021bie de 75% reciclate<\/strong> \u0219i exclusiv energie electric\u0103 regenerabil\u0103. Amprenta de carbon \u00een cazul utiliz\u0103rii o\u021belului XCarb\u00ae cu emisii reduse este <strong data-renderer-mark=\"true\">cu aproximativ 62% mai mic\u0103<\/strong> dec\u00e2t \u00een cazul solu\u021biilor standard \u00een care tabl\u0103 este acoperit\u0103 cu straturi organice.<\/p>\n<p data-renderer-start-pos=\"805\">\u00cen ciuda reducerii emisiilor de CO2, o\u021belul \u00ee\u0219i p\u0103streaz\u0103 <strong data-renderer-mark=\"true\">excelentele propriet\u0103\u021bi mecanice \u0219i de rezisten\u021b\u0103<\/strong>, comparabile cu produsele tradi\u021bionale din o\u021bel.<\/p>\n<div style=\"display: flex; align-items: center; padding-top: 10px;\">\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-98599 \" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2025\/05\/green-steel.png\" alt=\"\" width=\"106\" height=\"105\" srcset=\"https:\/\/bp2.eu\/wp-content\/uploads\/2025\/05\/green-steel.png 174w, https:\/\/bp2.eu\/wp-content\/uploads\/2025\/05\/green-steel-150x150.png 150w\" sizes=\"auto, (max-width: 106px) 100vw, 106px\" \/><\/p>\n<div><strong> Amprent\u0103 estimat\u0103 de CO2 pentru un acoperi\u0219 de 150 m\u00b2<br \/>\n<\/strong><em> \u2013 Pentru o\u021belul XCarb\u00ae cu emisii reduse: 712,5 kg CO2 echiv.<br \/>\n\u2013 Pentru tablele clasice cu acoperiri organice: 1879,5 kg CO2 echiv.<br \/>\n<\/em><\/div>\n<\/div>\n<div>\n<div><\/div>\n<\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"HERULIT HC\"><\/div>\n\n\n<h2 class=\"wp-block-heading\">HERCULIT HC<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                                <p class=\"variants__colorTitle uppercase\"><strong>Culori disponibile<\/strong><\/p>\n                                <div class=\"variants__colors\">\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #7c2b18\">\n                                                                                                                                                                                                                                                <\/span>\n                                            HC 3009\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #373c42\">\n                                                                                                                                                                                                                                                <\/span>\n                                            HC 7016\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #a55038\">\n                                                                                                                                                                                                                                                <\/span>\n                                            HC 8004\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #502a1d\">\n                                                                                                                                                                                                                                                <\/span>\n                                            HC 8017\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #1c1d1b\">\n                                                                                                                                                                                                                                                <\/span>\n                                            HC 9005\n                                                                                    <\/div>\n                                                                    <\/div>\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/03\/powloka-hc-www.jpg\" alt=\"HERCULIT [HC]\"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p>Acesta este un strat de acoperire dezvoltat \u00een str\u00e2ns\u0103 colaboreare cu unul din cei mai mari produc\u0103tori de lacuri \u0219i vopsele pentru coil coating din Europa. Mul\u0163i ani de studiu al tipurilor de straturi de acoperire utilizate p\u00e2n\u0103 acum \u015fi de monitorizare a nevoilor clien\u0163ilor, pun\u00e2nd accent deosebit pe nevoile montatorilor de acoperi\u015furi, ne-au permis s\u0103 concentr\u0103m at\u00e2t de multe avantaje diferite \u00eentr-un singur produs. <strong>HERCULIT [HC]<\/strong> este un poliester \u00eent\u0103rit cu poliuretan \u0219i rezisten\u0163\u0103 ridicat\u0103 la deteriorarea mecanic\u0103, grosime de 35 \u03bcm, rezistent\u0103 RUV4 \u0219i RC4<\/p>\n<div style=\"display: flex; align-items: center; padding-top: 10px;\">\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2702\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/11\/Obszar-roboczy-8.png\" alt=\"\" width=\"65\" height=\"auto\" \/><\/p>\n<div><b>\u2022 <\/b>Perioada de garan\u0163ie:<b> 40 de ani* <\/b>\u00a0<b><strong>\u00a0<\/strong><\/b><br \/>\n<b>\u2022 <\/b>Perioada de garan\u021bie pentru <b>IZI , ZET \u0219i FIT &#8211; 55 de ani<\/b><\/div>\n<\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-gray-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"ULTIMAT [UTK]\"><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">ULTIMAT [UTK]<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                                <p class=\"variants__colorTitle uppercase\"><strong>Culori disponibile<\/strong><\/p>\n                                <div class=\"variants__colors\">\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #024131\">\n                                                                                                                                                                                                                                                <\/span>\n                                            UTK 11\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #636464\">\n                                                                                                                                                                                                                                                <\/span>\n                                            UTK 23\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #32383a\">\n                                                                                                                                                                                                                                                <\/span>\n                                            UTK 24\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #a42b22\">\n                                                                                                                                                                                                                                                <\/span>\n                                            UTK 27\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #972820\">\n                                                                                                                                                                                                                                                <\/span>\n                                            UTK 28\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #50291d\">\n                                                                                                                                                                                                                                                <\/span>\n                                            UTK 31\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #3e1f16\">\n                                                                                                                                                                                                                                                <\/span>\n                                            UTK 32\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #1d1d1a\">\n                                                                                                                                                                                                                                                <\/span>\n                                            UTK 33\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #c24930\">\n                                                                                                                                                                                                                                                <\/span>\n                                            UTK 750\n                                                                                    <\/div>\n                                                                    <\/div>\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/03\/powloka-utktk-bw-www.jpg\" alt=\"ULTIMAT [UTK] \"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p>Un strat de acoperire cu grosimea de <strong>35 \u03bcm<\/strong> care are o rezisten\u021b\u0103 foarte mare la coroziune \u0219i la <strong>UV (RC4\/RUV4)<\/strong>. Caracteristica sa vizual\u0103 este structura sa granulat\u0103. A fost inspirat de natur\u0103 \u0219i, prin urmare, nu con\u021bine crom \u0219i metale grele \u0219i, fiind un produs ecologic, este reciclabil \u00een propor\u021bie de cel pu\u021bin <strong>80%.<\/strong> Pl\u0103cile acoperite cu stratul flexibil <strong>ULTIMAT [UTK]<\/strong> pot fi profilate la temperaturi extrem de sc\u0103zute.<\/p>\n<div style=\"display: flex; align-items: center; padding-top: 10px;\">\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2702\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/11\/Obszar-roboczy-8.png\" alt=\"\" width=\"65\" height=\"auto\" \/><\/p>\n<div>\u2022 Perioada de garan\u0163ie: <strong>20 de ani<\/strong>.<br \/>\n\u2022 perioada de garan\u021bie <strong>MODULAR SERIES<\/strong> \u0219i <strong>FIT &#8211; 30 de ani<\/strong>.<\/div>\n<\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"POLIESTER Standard [RAL]\"><\/div>\n\n\n<h2 class=\"wp-block-heading\">POLIESTER Standard [RAL]<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                                <p class=\"variants__colorTitle uppercase\"><strong>Culori disponibile<\/strong><\/p>\n                                <div class=\"variants__colors\">\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #decd8e\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 1002\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #eadfbb\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 1015\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #ca3027\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.7]<\/span>\n                                                                                                                                                <\/span>\n                                            RAL 3000\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #7e2224\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 3005\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #7d2b17\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 3009\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #8c241b\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.7]<\/span>\n                                                                                                                                                <\/span>\n                                            RAL 3011\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #0c507e\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.7]<\/span>\n                                                                                                                                                <\/span>\n                                            RAL 5010\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #004b35\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 6005\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #657a59\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 6011\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #216d41\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 6020\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #008043\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 6029\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #283539\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.7]<\/span>\n                                                                                                                                                <\/span>\n                                            RAL 7016\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #2c434f\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.7]<\/span>\n                                                                                                                                                <\/span>\n                                            RAL 7024\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #d2d6d3\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.7]<\/span>\n                                                                                                                                                <\/span>\n                                            RAL 7035\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #a65037\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 8004\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #4a251c\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.7]<\/span>\n                                                                                                                                                <\/span>\n                                            RAL 8017\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #3d261e\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 8019\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #e3e8de\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.6]<br>[0.7]<\/span>\n                                                                                                                                                <\/span>\n                                            RAL 9002\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #1d1d1b\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 9005\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #b3b5b3\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.6]<br>[0.7]<br>[1.0]<\/span>\n                                                                                                                                                <\/span>\n                                            RAL 9006\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #9e9d9e\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.7]<\/span>\n                                                                                                                                                <\/span>\n                                            RAL 9007\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #fffef7\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.7]<br>[1.0]<\/span>\n                                                                                                                                                <\/span>\n                                            RAL 9010\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                    <\/div>\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/03\/powloka-ral-www-gloss-3.jpg\" alt=\"POLIESTER Standard [RAL] \"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p>Strat de acoperire organic\u0103 de baz\u0103 cu o grosime de <strong>25 \u03bcm.<\/strong> Suprafa\u0163a este uniform\u0103, neted\u0103 &#8211; lucioas\u0103 sau metalic\u0103. Un material cu spectru foarte larg de aplicare. Este oferit \u00eentr-o gam\u0103 larg\u0103 de culori descrise conform cu standardul universal <strong>RAL.<\/strong><\/p>\n<div style=\"display: flex; align-items: center; padding-top: 10px;\">\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2702\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/11\/Obszar-roboczy-8.png\" alt=\"\" width=\"65\" height=\"auto\" \/><\/p>\n<div>Perioada de garan\u0163ie<b>: 10 de ani*\u00a0<\/b><\/div>\n<\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"POLIESTER Interior [INT]\"><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">POLIESTER Interior [INT]<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                                <p class=\"variants__colorTitle uppercase\"><strong>Culori disponibile<\/strong><\/p>\n                                <div class=\"variants__colors\">\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #f4f4ed\">\n                                                                                                                                                                                                                                                <\/span>\n                                            INT 9010\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #d7d5cc\">\n                                                                                                                                                                                                                                                <\/span>\n                                            INT 9002\n                                                                                    <\/div>\n                                                                    <\/div>\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/03\/powloka-int-www.jpg\" alt=\"POLIESTER Interior [INT]\"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p>Tabl\u0103 acoperit\u0103 cu un strat de poliester de <strong>15 \u03bcm<\/strong> cu o suprafa\u0163\u0103 neted\u0103 \u015fi str\u0103lucitoare. Datorit\u0103 grosimii reduse a \u00eenveli\u015fului organic, aceasta este destinat\u0103 \u00een principal aplica\u0163iilor interioare \u015fi elementelor de construc\u0163ie care nu sunt expuse direct condi\u0163iilor meteo.<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"MULTILAYER [MLT]\"><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">MULTILAYER [MLT]<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                                <p class=\"variants__colorTitle uppercase\"><strong>Culori disponibile<\/strong><\/p>\n                                <div class=\"variants__colors\">\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #cebeae\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.6]<\/span>\n                                                                                                                                                <\/span>\n                                            SL252 Winchester\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #49331c\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.6]<\/span>\n                                                                                                                                                <\/span>\n                                            SL59 Dark Oak\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #a76529\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.6]<\/span>\n                                                                                                                                                <\/span>\n                                            SL65 Golden Oak\n                                                                                    <\/div>\n                                                                    <\/div>\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/03\/powloka-ml-www.png\" alt=\"MULTILAYER [MLT]\"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p>Lac de poliester gros de <strong>40 \u03bcm<\/strong> cu un strat de zinc <strong>Z275<\/strong> sau zinc-magneziu <strong>ZM120<\/strong>. Se caracterizeaz\u0103 printr-un aspect similar lemnului si o protec\u0163ie adecvat\u0103 \u00eempotriva coroziunii \u015fi a radia\u0163iilor <strong>UV<\/strong>. O astfel de combina\u0163ie permite utilizarea sa extern\u0103, \u00een special acolo unde este necesar\u0103 o rezisten\u0163\u0103 ridicat\u0103 la condi\u0163iile meteo \u015fi un nivel estetic ridicat.<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-gray-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"ALUZINC [AZ]\"><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">ALUZINC [AZ]<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                                <p class=\"variants__colorTitle uppercase\"><strong>Culori disponibile<\/strong><\/p>\n                                <div class=\"variants__colors\">\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #d5dbda\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.7]<br>[1.0]<\/span>\n                                                                                                                                                <\/span>\n                                            ALUZINC [AZ] \n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                    <\/div>\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/03\/powloka-aluzinc-www.jpg\" alt=\"ALUZINC [AZ]\"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p>Este o tabl\u0103 din o\u0163el acoperit\u0103 pe ambele p\u0103r\u0163i cu un aliaj de aluminiu \u015fi zinc \u00eentr-un proces similar cu galvanizarea la cald. Datorit\u0103 acestui fapt, \u00eendepline\u015fte cele mai \u00eenalte cerin\u0163e de rezisten\u0163\u0103 la coroziune atmosferic\u0103 \u015fi coroziune \u00een medii umede. \u00cen plus, are un strat protector de polimer &#8222;EASYFILM&#8221;.<\/p>\n<div style=\"display: flex; align-items: center; padding-top: 10px;\">\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2702\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/11\/Obszar-roboczy-8.png\" alt=\"\" width=\"65\" height=\"auto\" \/><\/p>\n<div>Perioada de garan\u0163ie<b>: 25 de ani*\u00a0<\/b><\/div>\n<\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"ZINC [ZN]\"><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">ZINC [ZN]<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                                <p class=\"variants__colorTitle uppercase\"><strong>Culori disponibile<\/strong><\/p>\n                                <div class=\"variants__colors\">\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #bfcbd2\">\n                                                                                                                                                    <span style=\"position: relative;\">[0.6-1.0]<\/span>\n                                                                                                                                                <\/span>\n                                            ZINC [ZN]\n                                                                                            <div class=\"tooltip tooltip--large\">Disponibil \u0219i \u00een grosime de 0,5 mm<\/div>\n                                                                                    <\/div>\n                                                                    <\/div>\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/03\/powloka-ocynk-www.jpeg\" alt=\"ZINC [ZN]\"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p>Tabla este zincat\u0103 la cald pe ambele p\u0103r\u0163i printr-un proces continuu, care protejeaz\u0103 miezul dein o\u0163el \u00eempotriva coroziunii. Aceasta se caracterizeaz\u0103 printr-o suprafa\u0163\u0103 neted\u0103 \u015fi uniform\u0103, care satisface \u015fi cele mai mari cerin\u0163e estetice.<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"O\u021bel cu acoperire organic\u0103 [HDS]\"><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">O\u021bel cu acoperire organic\u0103 [HDS]<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                                <p class=\"variants__colorTitle uppercase\"><strong>Culori disponibile<\/strong><\/p>\n                                <div class=\"variants__colors\">\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #e0cd8b\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 1002\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #ebe1bc\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 1015\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #c93326\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 3000\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #7d2224\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 3005\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #7d2d16\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 3009\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #8c251c\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 3011\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #22507f\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 5010\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #204d36\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 6005\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #677c59\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 6011\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #326f42\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 6020\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #3b8141\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 6029\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #29343a\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 7016\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #2d424f\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 7024\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #d2d8d5\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 7035\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #a44f38\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 8004\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #4b271b\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 8017\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #3d271d\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 8019\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #e4e9df\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 9002\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #1d1d1b\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 9005\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #b4b5b4\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 9006\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #9e9f9f\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 9007\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--light\" style=\"background-color: #fffff8\">\n                                                                                                                                                                                                                                                <\/span>\n                                            RAL 9010\n                                                                                    <\/div>\n                                                                    <\/div>\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/07\/powloka-hds-www.jpg\" alt=\"Stal powlekana organicznie [HDS]\"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p>Producem casete \u0219i panouri de fa\u021bad\u0103 din o\u021bel cu acoperire organic\u0103 HDS cu un strat de 35 \u00b5m, care are o rezisten\u021b\u0103 foarte bun\u0103 la coroziune p\u00e2n\u0103 la RC4 \u0219i rezisten\u021b\u0103 la UV p\u00e2n\u0103 la RUV4. \u00cen func\u021bie de tipul de mediu extern, se ob\u021bin garan\u021bii de p\u00e2n\u0103 la 20 de ani. \u00cen plus, oferta este extins\u0103 pentru a include acoperirea cu vopsea pulbere disponibil\u0103 \u00een \u00eentreaga palet\u0103 RAL pentru mat \u0219i satinat, a c\u0103rei acoperire este de 60 \u00b5m \u0219i are marca de calitate QUALICOAT.<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"ICE COVER ZM [ICep]\"><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">ICE COVER ZM [ICep]<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                                <p class=\"variants__colorTitle uppercase\"><strong>Culori disponibile<\/strong><\/p>\n                                <div class=\"variants__colors\">\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #636563\">\n                                                                                                                                                                                                                                                <\/span>\n                                            ICep 23\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #97281f\">\n                                                                                                                                                                                                                                                <\/span>\n                                            ICep 28\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #3f1f14\">\n                                                                                                                                                                                                                                                <\/span>\n                                            ICep 32\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #1d1d1b\">\n                                                                                                                                                                                                                                                <\/span>\n                                            ICep 33\n                                                                                    <\/div>\n                                                                            <div class=\"variants__color tooltip__wrapper\">\n                                            <span class=\"variant__colorDot variant__colorDot--dark\" style=\"background-color: #c1492f\">\n                                                                                                                                                                                                                                                <\/span>\n                                            ICep 750\n                                                                                    <\/div>\n                                                                    <\/div>\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/03\/powloka-icep-www.jpg\" alt=\"ICE COVER ZM [ICep]\"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p>Strat de acoperire organic gros <strong>(35 \u03bcm)<\/strong> de textur\u0103 interesant\u0103, cristalin\u0103, asem\u0103n\u0103toare vopselei groase. Miezul este din o\u0163el acoperit cu un aliaj de zinc, care asigur\u0103 protec\u0163ie sporit\u0103 \u00eempotriva coroziunii. Rezultatul este o rezisten\u0163\u0103 semnificativ crescut\u0103 la coroziunea alb\u0103 \u015fi ro\u015fie \u00een mediu <strong>RC3.<\/strong><\/p>\n<div style=\"display: flex; align-items: center; padding-top: 10px;\">\n<p><img decoding=\"async\" class=\"alignleft size-thumbnail wp-image-2702\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/11\/Obszar-roboczy-8.png\" alt=\"\" width=\"65\" height=\"auto\" \/><\/p>\n<div>Perioada de garan\u021bie<strong>: 35 ani *<br \/>\n<\/strong><em>*Condi\u0163iile detaliate ale garan\u0163iei<br \/>\nsunt specificate \u00een certificatul de garan\u0163ie.<\/em><\/div>\n<\/div>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-gray-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"MARKERBOARD [M]\"><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">MARKERBOARD [M]<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/03\/powloka-m9129-www.jpg\" alt=\"MARKERBOARD [M]\"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p>Strat de acoperire destinat fabric\u0103rii unor diferite tipuri de tabl\u0103 cu \u015ftergere uscat\u0103. Este produs pe baz\u0103 de material brut zincat \u015fi acoperit cu un lac special de tip Markerboard. Suprafa\u0163a are un luciu de 80-90 GU \u015fi o duritate de 2H. Este acoperit cu o folie de protec\u0163ie.<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"CHALKBOARD [C]\"><\/div>\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">CHALKBOARD [C]<\/h2>\n\n\n\n    <div class=\"variants__wrapper\">\n                        <div class=\"variants__slidesWrapper\">\n            <div class=\"variants__slides sliderGroup\">\n                                                        <div class=\"variants__slide sliderGroup__elem\">\n                        <div class=\"variants__slideInner\">\n                            <div class=\"variants__colorsWrapper\">\n                                                            <\/div>\n                            <div class=\"variants__contentWrapper\">\n                                <figure class=\"variants__image\"><img decoding=\"async\" src=\"https:\/\/bp2.eu\/wp-content\/uploads\/2022\/03\/powloka-chalk-www.jpg\" alt=\"CHALKBOARD [C]\"><\/figure>\n                                <div class=\"variants__content\">\n                                    <p>Strat de acoperire destinat fabric\u0103rii diverselor tipuri de tabl\u0103 ce poate fi cur\u0103\u0163at prin sp\u0103lare. Este produs pe baza de material zincat \u015fi acoperit cu un lac tip <strong>Chalkboard<\/strong>, care permite scrierea pe el cu cret\u0103. Este protejat suplimentar cu folie.<\/p>\n                                                                    <\/div>\n                            <\/div>\n                        <\/div>\n\n                    <\/div>\n                            <\/div>\n        <\/div>\n            <\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-group has-white-background-color has-background\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\r\n<div class=\"section__data\" data-section=\"Propriet\u0103\u0163ile straturilor de protec\u0163ie\"><\/div>\n\n\n<style data-wp-block-html=\"css\">\n.coatings-properties-box {\n  width: 100%;\n  font-family: inherit;\n}\n\n.coatings-properties-box h2 {\n  margin: 0 0 35px;\n  font-size: clamp(36px, 5vw, 64px);\n  line-height: 1;\n  color: #e4311b;\n  font-weight: 800;\n}\n\n.coatings-properties-note {\n  margin: 0 0 35px;\n  font-size: 14px;\n  font-weight: 700;\n}\n\n.coatings-properties-wrap {\n  width: 100%;\n  background: #eee;\n  padding: 35px 30px;\n  overflow-x: auto;\n  -webkit-overflow-scrolling: touch;\n  box-sizing: border-box;\nscrollbar-color: #000 #ddd;\n  scrollbar-width: thin;\n}\n\n.coatings-properties-table {\n  width: 100%;\n  min-width: 680px;\n  border-collapse: collapse;\n  font-size: 14px;\n  color: #000;\n}\n\n.coatings-properties-table th,\n.coatings-properties-table td {\n  padding: 12px 10px;\n  border-right: 1px solid #000;\n  border-bottom: 1px solid #000;\n  vertical-align: middle;\n  text-align: center;\n}\n\n.coatings-properties-table th:last-child,\n.coatings-properties-table td:last-child {\n  border-right: none;\n}\n\n.coatings-properties-table thead th {\n  border-top: 1px solid #000;\n  font-weight: 800;\n}\n\n.coatings-properties-table th:first-child,\n.coatings-properties-table td:first-child {\n  text-align: left;\n  font-weight: 800;\n}\n\n@media (max-width: 600px) {\n  .coatings-properties-wrap {\n    padding: 25px 18px;\n  }\n\n  .coatings-properties-box h2 {\n    margin-bottom: 25px;\n  }\n\n  .coatings-properties-note {\n    margin-bottom: 25px;\n  }\n\n  .coatings-properties-table {\n    font-size: 13px;\n  }\n\n  .coatings-properties-table th,\n  .coatings-properties-table td {\n    padding: 10px 8px;\n  }\n}\n<\/style>\n\n<div class=\"coatings-properties-box\">\n  <h2>Propriet\u0103\u0163ile straturilor de protec\u0163ie<\/h2>\n  <p class=\"coatings-properties-note\">Tabelul de mai jos are un caracter orientativ.<\/p>\n\n  <div class=\"coatings-properties-wrap\">\n    <table class=\"coatings-properties-table\">\n      <thead>\n        <tr>\n          <th>Cod<\/th>\n          <th>Grosimea stratului de acoperire<\/th>\n          <th>Rezisten\u021b\u0103 la<br>coroziune<\/th>\n          <th>Rezisten\u021b\u0103 la<br>radia\u021bii UV<\/th>\n          <th>Perioada de garan\u021bie<br>(ani)<\/th>\n        <\/tr>\n      <\/thead>\n      <tbody>\n        <tr>\n          <td>Galvanizat [ZN]<\/td>\n          <td>200 g\/m\u00b2<br>275 g\/m\u00b2<\/td>\n          <td>RC2<\/td>\n          <td>Nu se aplic\u0103<\/td>\n          <td>Nu se aplic\u0103<\/td>\n        <\/tr>\n        <tr>\n          <td>Aluzinc [AZ 150]<\/td>\n          <td>150 g\/m\u00b2<\/td>\n          <td>RC2<\/td>\n          <td>Nu se aplic\u0103<\/td>\n          <td>Nu se aplic\u0103<\/td>\n        <\/tr>\n        <tr>\n          <td>POLYESTER Interior [INT]<\/td>\n          <td>15 \u00b5m<\/td>\n          <td>RA2<\/td>\n          <td>Nu se aplic\u0103<\/td>\n          <td>Nu se aplic\u0103<\/td>\n        <\/tr>\n        <tr>\n          <td>POLYESTER Standard [RAL]<\/td>\n          <td>25 \u00b5m<\/td>\n          <td>RC3<\/td>\n          <td>RUV2<\/td>\n          <td>10<\/td>\n        <\/tr>\n        <tr>\n          <td>MULTILAYER 40 [MLT]<\/td>\n          <td>40 \u00b5m<\/td>\n          <td>RC3<\/td>\n          <td>RUV3<\/td>\n          <td>10<\/td>\n        <\/tr>\n        <tr>\n          <td>MAT 35 Standard [TK]<\/td>\n          <td>35 \u00b5m<\/td>\n          <td>RC3<\/td>\n          <td>RUV3<\/td>\n          <td>15<\/td>\n        <\/tr>\n        <tr>\n          <td>ULTIMAT [UTK]<\/td>\n          <td>35 \u00b5m<\/td>\n          <td>RC4<\/td>\n          <td>RUV4<\/td>\n          <td>20, 30*<\/td>\n        <\/tr>\n        <tr>\n          <td>Aluzinc [AZ 185]<\/td>\n          <td>185 g\/m\u00b2<\/td>\n          <td>RC3<\/td>\n          <td>Nu se aplic\u0103<\/td>\n          <td>25<\/td>\n        <\/tr>\n        <tr>\n          <td>HERCULIT [HC]<\/td>\n          <td>35 \u00b5m<\/td>\n          <td>RC4<\/td>\n          <td>RUV4<\/td>\n          <td>40 [IZI], ZET, FIT &#8211; 55*]<\/td>\n        <\/tr>\n      <\/tbody>\n    <\/table>\n\n  <\/div>\n<p>*Se aplic\u0103 \u0163iglei metalice modulare IZI \u015fi ZET<\/p>\n<\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n\n\n\r\n<div class=\"section__data\" data-section=\"Disponibilitatea straturilor de protec\u0163ie\"><\/div>\n\n\n<style data-wp-block-html=\"css\">\n.coatings-availability-box {\n  width: 100%;\n  font-family: inherit;\n}\n\n.coatings-availability-box h2 {\n  margin: 0 0 35px;\n  font-size: clamp(36px, 5vw, 64px);\n  line-height: 1;\n  color: #e4311b;\n  font-weight: 800;\n}\n\n.coatings-availability-note {\n  margin: 0 0 35px;\n  font-size: 14px;\n  font-weight: 700;\n}\n\n.coatings-availability-wrap {\n  width: 100%;\n  background: #eee;\n  padding: 35px 30px;\n  overflow-x: auto;\n  -webkit-overflow-scrolling: touch;\n  box-sizing: border-box;\nscrollbar-color: #000 #ddd;\n  scrollbar-width: thin;\n}\n\n.coatings-availability-table {\n  width: 100%;\n  min-width: 760px;\n  border-collapse: collapse;\n  font-size: 14px;\n  color: #000;\n}\n\n.coatings-availability-table th,\n.coatings-availability-table td {\n  padding: 12px 10px;\n  border-right: 1px solid #000;\n  border-bottom: 1px solid #000;\n  vertical-align: middle;\n  text-align: center;\n}\n\n.coatings-availability-table th:last-child,\n.coatings-availability-table td:last-child {\n  border-right: none;\n}\n\n.coatings-availability-table thead th {\n  border-top: 1px solid #000;\n  font-weight: 800;\n}\n\n.coatings-availability-table th:first-child,\n.coatings-availability-table td:first-child {\n  text-align: left;\n  font-weight: 800;\n}\n\n.coatings-availability-table .mark {\n  font-size: 18px;\n  line-height: 1;\n}\n\n@media (max-width: 600px) {\n  .coatings-availability-wrap {\n    padding: 25px 18px;\n  }\n\n  .coatings-availability-box h2 {\n    margin-bottom: 25px;\n  }\n\n  .coatings-availability-note {\n    margin-bottom: 25px;\n  }\n\n  .coatings-availability-table {\n    font-size: 13px;\n  }\n\n  .coatings-availability-table th,\n  .coatings-availability-table td {\n    padding: 10px 8px;\n  }\n}\n<\/style>\n\n<div class=\"coatings-availability-box\">\n  <h2>Disponibilitatea straturilor de protec\u0163ie<\/h2>\n  <p class=\"coatings-availability-note\">Tabelul de mai jos are un caracter orientativ.<\/p>\n\n  <div class=\"coatings-availability-wrap\">\n    <table class=\"coatings-availability-table\">\n      <thead>\n        <tr>\n          <th>Cod<\/th>\n          <th>ZN<\/th>\n          <th>AZ 150<\/th>\n          <th>INT<\/th>\n          <th>RAL<\/th>\n          <th>AZ 185<\/th>\n          <th>TK<\/th>\n          <th>UTK<\/th>\n          <th>HC<\/th>\n        <\/tr>\n      <\/thead>\n      <tbody>\n        <tr>\n          <td>Grosimea stratului de acoperire<\/td>\n          <td>200\/275<br>g\/m\u00b2<\/td>\n          <td>150<br>g\/m\u00b2<\/td>\n          <td>15 \u00b5m<\/td>\n          <td>25 \u00b5m<\/td>\n          <td>185 g\/m\u00b2<\/td>\n          <td>35 \u00b5m<\/td>\n          <td>35 \u00b5m<\/td>\n          <td>35 \u00b5m<\/td>\n        <\/tr>\n        <tr>\n          <td>MODULAR SERIES<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n        <\/tr>\n        <tr>\n          <td>COMPACT SERIES<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a0*<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n        <\/tr>\n        <tr>\n          <td>CLASSIC SERIES<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n        <\/tr>\n        <tr>\n          <td>PANEL SERIES<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n        <\/tr>\n        <tr>\n          <td>Table cutate trapezoidal<br>T7 p\u00e2n\u0103 la T18 \/ T18 ECO<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n        <\/tr>\n        <tr>\n          <td>Table cutate trapezoidal<br>T35 p\u00e2n\u0103 la T55<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n        <\/tr>\n        <tr>\n          <td>Table cutate trapezoidal<br>T60<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n        <\/tr>\n        <tr>\n          <td>Table cutate trapezoidal<br>T80 p\u00e2n\u0103 la T160<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a0<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n          <td class=\"mark\">\u25a1<\/td>\n        <\/tr>\n      <\/tbody>\n    <\/table>\n  <\/div>\n<p>*Cu excep\u021bia \u021biglei metalice compacte IZI 2.0.<\/p>\n<\/div>\n<\/div><\/div>\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer is-style-smaller-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Sunt lucruri care trebuie s\u0103 fie rezistente PELICULE, CULORI \u0218I GARAN\u021aII Sunt mai mul\u021bi factori care influen\u021beaz\u0103 calitatea unui acoperi\u0219. Acesta trebuie s\u0103 fie durabil, capabil s\u0103 reziste la condi\u021bii meteo, s\u0103 reziste bine la perioadele calde \u0219i reci ale anului \u0219i, \u00een plus, trebuie s\u0103 fie pl\u0103cut din punct de vedere estetic. Vopselele, \u0219i [&hellip;]<\/p>\n","protected":false},"author":14,"featured_media":0,"parent":0,"menu_order":33,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-83450","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/bp2.eu\/ro\/wp-json\/wp\/v2\/pages\/83450","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bp2.eu\/ro\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bp2.eu\/ro\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bp2.eu\/ro\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/bp2.eu\/ro\/wp-json\/wp\/v2\/comments?post=83450"}],"version-history":[{"count":1,"href":"https:\/\/bp2.eu\/ro\/wp-json\/wp\/v2\/pages\/83450\/revisions"}],"predecessor-version":[{"id":107899,"href":"https:\/\/bp2.eu\/ro\/wp-json\/wp\/v2\/pages\/83450\/revisions\/107899"}],"wp:attachment":[{"href":"https:\/\/bp2.eu\/ro\/wp-json\/wp\/v2\/media?parent=83450"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}